{"id":196685,"date":"2026-02-23T17:17:52","date_gmt":"2026-02-23T17:17:52","guid":{"rendered":"https:\/\/iber.market\/producto\/cacao-soluble-colacao-original-2\/"},"modified":"2026-02-23T17:17:53","modified_gmt":"2026-02-23T17:17:53","slug":"cacao-soluble-colacao-original-2","status":"publish","type":"product","link":"https:\/\/iber.market\/nl\/product-2\/cacao-soluble-colacao-original-2\/","title":{"rendered":"Cacao soluble ColaCao original"},"content":{"rendered":"<p>Cacao soluble ColaCao original es perfecto para quienes viven fuera de Espa\u00f1a y desean seguir disfrutando de sabores habituales del caf\u00e9, cacao e infusiones presentes en la cultura gastron\u00f3mica espa\u00f1ola. Ideal para desayunos, pausas o momentos de relax manteniendo el v\u00ednculo con Espa\u00f1a. Una opci\u00f3n pensada para expatriados espa\u00f1oles y consumidores europeos que valoran productos alimentarios t\u00edpicos de Espa\u00f1a.<\/p>","protected":false},"excerpt":{"rendered":"<p>Cacao soluble ColaCao original con aut\u00e9ntico sabor espa\u00f1ol. Ideal para expatriados en Europa y amantes de la gastronom\u00eda espa\u00f1ola que buscan productos tradicionales.<\/p>","protected":false},"featured_media":196686,"template":"","meta":[],"product_brand":[],"product_cat":[103],"product_tag":[],"class_list":{"0":"post-196685","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-cacao-y-chocolate-soluble","8":"first","9":"instock","10":"taxable","11":"shipping-taxable","12":"purchasable","13":"product-type-simple"},"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/iber.market\/nl\/wp-json\/wp\/v2\/product\/196685","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/iber.market\/nl\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/iber.market\/nl\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/iber.market\/nl\/wp-json\/wp\/v2\/media\/196686"}],"wp:attachment":[{"href":"https:\/\/iber.market\/nl\/wp-json\/wp\/v2\/media?parent=196685"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/iber.market\/nl\/wp-json\/wp\/v2\/product_brand?post=196685"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/iber.market\/nl\/wp-json\/wp\/v2\/product_cat?post=196685"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/iber.market\/nl\/wp-json\/wp\/v2\/product_tag?post=196685"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}