{"id":192502,"date":"2026-02-17T08:58:22","date_gmt":"2026-02-17T08:58:22","guid":{"rendered":"https:\/\/iber.market\/producto\/cerveza-00-sin-alcohol-tostada-falke\/"},"modified":"2026-03-03T14:17:05","modified_gmt":"2026-03-03T14:17:05","slug":"cerveza-00-sin-alcohol-tostada-falke","status":"publish","type":"product","link":"https:\/\/iber.market\/it\/product-2\/cerveza-00-sin-alcohol-tostada-falke\/","title":{"rendered":"Birra 0,0% analcolica arrostita Falke"},"content":{"rendered":"<p>Cerveza 0,0% sin alcohol tostada Falke es una excelente opci\u00f3n para quienes buscan productos t\u00edpicos de Espa\u00f1a en Europa. Pensado especialmente para expatriados, residentes europeos o cualquier amante de la gastronom\u00eda y bebidas espa\u00f1olas, este producto destaca por su calidad, sabor aut\u00e9ntico y tradici\u00f3n. Perfecto para compartir, regalar o disfrutar en casa con la esencia del estilo de vida espa\u00f1ol.<\/p>","protected":false},"excerpt":{"rendered":"<p>Cerveza 0,0% sin alcohol tostada Falke ideal para disfrutar del aut\u00e9ntico sabor de Espa\u00f1a. Perfecto para expatriados y amantes europeos de la gastronom\u00eda y bebidas espa\u00f1olas.<\/p>","protected":false},"featured_media":192503,"template":"","meta":[],"product_brand":[],"product_cat":[47],"product_tag":[],"class_list":{"0":"post-192502","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-cervezas-espanolas","8":"first","9":"instock","10":"taxable","11":"shipping-taxable","12":"purchasable","13":"product-type-simple"},"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/iber.market\/it\/wp-json\/wp\/v2\/product\/192502","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/iber.market\/it\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/iber.market\/it\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/iber.market\/it\/wp-json\/wp\/v2\/media\/192503"}],"wp:attachment":[{"href":"https:\/\/iber.market\/it\/wp-json\/wp\/v2\/media?parent=192502"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/iber.market\/it\/wp-json\/wp\/v2\/product_brand?post=192502"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/iber.market\/it\/wp-json\/wp\/v2\/product_cat?post=192502"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/iber.market\/it\/wp-json\/wp\/v2\/product_tag?post=192502"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}