{"id":192330,"date":"2026-02-17T08:57:02","date_gmt":"2026-02-17T08:57:02","guid":{"rendered":"https:\/\/iber.market\/producto\/cava-brut-nature-reserva-vintage-cabre-sabate\/"},"modified":"2026-07-31T07:35:36","modified_gmt":"2026-07-31T07:35:36","slug":"cava-brut-nature-reserva-vintage-cabre-sabate","status":"publish","type":"product","link":"https:\/\/iber.market\/it\/product-2\/cava-brut-nature-reserva-vintage-cabre-sabate\/","title":{"rendered":"Cava brut nature reserva vintage Cabr\u00e9 &#038; Sabat\u00e9"},"content":{"rendered":"<p>Cava brut nature reserva vintage Cabr\u00e9 &#038; Sabat\u00e9 es una excelente opci\u00f3n para quienes buscan productos t\u00edpicos de Espa\u00f1a en Europa. Pensado especialmente para expatriados, residentes europeos o cualquier amante de la gastronom\u00eda y bebidas espa\u00f1olas, este producto destaca por su calidad, sabor aut\u00e9ntico y tradici\u00f3n. Perfecto para compartir, regalar o disfrutar en casa con la esencia del estilo de vida espa\u00f1ol.<\/p>","protected":false},"excerpt":{"rendered":"<p>Cava brut nature reserva vintage Cabr\u00e9 &#038; Sabat\u00e9 ideal para disfrutar del aut\u00e9ntico sabor de Espa\u00f1a. Perfecto para expatriados y amantes europeos de la gastronom\u00eda y bebidas espa\u00f1olas.<\/p>","protected":false},"featured_media":192331,"template":"","meta":[],"product_brand":[],"product_cat":[375],"product_tag":[],"class_list":["post-192330","product","type-product","status-publish","has-post-thumbnail","product_cat-cavas-y-espumosos","first","instock","taxable","shipping-taxable","purchasable","product-type-simple"],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/iber.market\/it\/wp-json\/wp\/v2\/product\/192330","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/iber.market\/it\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/iber.market\/it\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/iber.market\/it\/wp-json\/wp\/v2\/media\/192331"}],"wp:attachment":[{"href":"https:\/\/iber.market\/it\/wp-json\/wp\/v2\/media?parent=192330"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/iber.market\/it\/wp-json\/wp\/v2\/product_brand?post=192330"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/iber.market\/it\/wp-json\/wp\/v2\/product_cat?post=192330"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/iber.market\/it\/wp-json\/wp\/v2\/product_tag?post=192330"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}