{"id":196217,"date":"2026-02-23T13:57:05","date_gmt":"2026-02-23T13:57:05","guid":{"rendered":"https:\/\/iber.market\/producto\/pan-tostado-vitalite-wasa\/"},"modified":"2026-02-23T13:57:05","modified_gmt":"2026-02-23T13:57:05","slug":"pan-tostado-vitalite-wasa","status":"publish","type":"product","link":"https:\/\/iber.market\/fr\/product\/pan-tostado-vitalite-wasa\/","title":{"rendered":"Pan tostado vitalit\u00e9 Wasa"},"content":{"rendered":"<p>Pan tostado vitalit\u00e9 Wasa es perfecto para quienes viven fuera de Espa\u00f1a y quieren seguir disfrutando del sabor tradicional de la panader\u00eda y reposter\u00eda espa\u00f1ola. Inspirado en recetas habituales de Espa\u00f1a, resulta ideal para desayunos, meriendas o momentos dulces manteniendo el v\u00ednculo con la cultura gastron\u00f3mica espa\u00f1ola. Una opci\u00f3n pensada para expatriados y consumidores europeos que valoran los productos t\u00edpicos de Espa\u00f1a.<\/p>","protected":false},"excerpt":{"rendered":"<p>Pan tostado vitalit\u00e9 Wasa con aut\u00e9ntico sabor de la panader\u00eda y reposter\u00eda espa\u00f1ola. Ideal para expatriados en Europa y amantes de la gastronom\u00eda espa\u00f1ola.<\/p>","protected":false},"featured_media":196218,"template":"","meta":[],"product_brand":[],"product_cat":[192],"product_tag":[],"class_list":{"0":"post-196217","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-pan-tostado-y-rallado","8":"first","9":"instock","10":"taxable","11":"shipping-taxable","12":"purchasable","13":"product-type-simple"},"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/iber.market\/fr\/wp-json\/wp\/v2\/product\/196217","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/iber.market\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/iber.market\/fr\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/iber.market\/fr\/wp-json\/wp\/v2\/media\/196218"}],"wp:attachment":[{"href":"https:\/\/iber.market\/fr\/wp-json\/wp\/v2\/media?parent=196217"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/iber.market\/fr\/wp-json\/wp\/v2\/product_brand?post=196217"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/iber.market\/fr\/wp-json\/wp\/v2\/product_cat?post=196217"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/iber.market\/fr\/wp-json\/wp\/v2\/product_tag?post=196217"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}