{"id":200942,"date":"2026-03-03T14:17:17","date_gmt":"2026-03-03T14:17:17","guid":{"rendered":"https:\/\/iber.market\/producto\/cerveza-especial-san-miguel-2\/"},"modified":"2026-07-31T07:36:05","modified_gmt":"2026-07-31T07:36:05","slug":"cerveza-especial-san-miguel-2","status":"publish","type":"product","link":"https:\/\/iber.market\/en\/product\/cerveza-especial-san-miguel-2\/","title":{"rendered":"Cerveza especial San Miguel"},"content":{"rendered":"<p>Cerveza especial San Miguel es una excelente opci\u00f3n para quienes buscan productos t\u00edpicos de Espa\u00f1a en Europa. Pensado especialmente para expatriados, residentes europeos o cualquier amante de la gastronom\u00eda y bebidas espa\u00f1olas, este producto destaca por su calidad, sabor aut\u00e9ntico y tradici\u00f3n. Perfecto para compartir, regalar o disfrutar en casa con la esencia del estilo de vida espa\u00f1ol.<\/p>","protected":false},"excerpt":{"rendered":"<p>Cerveza especial San Miguel ideal para disfrutar del aut\u00e9ntico sabor de Espa\u00f1a. Perfecto para expatriados y amantes europeos de la gastronom\u00eda y bebidas espa\u00f1olas.<\/p>","protected":false},"featured_media":200943,"template":"","meta":[],"product_brand":[],"product_cat":[47],"product_tag":[],"class_list":["post-200942","product","type-product","status-publish","has-post-thumbnail","product_cat-cervezas-espanolas","first","instock","taxable","shipping-taxable","purchasable","product-type-simple"],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/iber.market\/en\/wp-json\/wp\/v2\/product\/200942","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/iber.market\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/iber.market\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/iber.market\/en\/wp-json\/wp\/v2\/media\/200943"}],"wp:attachment":[{"href":"https:\/\/iber.market\/en\/wp-json\/wp\/v2\/media?parent=200942"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/iber.market\/en\/wp-json\/wp\/v2\/product_brand?post=200942"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/iber.market\/en\/wp-json\/wp\/v2\/product_cat?post=200942"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/iber.market\/en\/wp-json\/wp\/v2\/product_tag?post=200942"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}