{"id":195023,"date":"2026-02-21T22:26:24","date_gmt":"2026-02-21T22:26:24","guid":{"rendered":"https:\/\/iber.market\/producto\/bebida-de-avena-alitey-3\/"},"modified":"2026-06-04T07:00:00","modified_gmt":"2026-06-04T07:00:00","slug":"bebida-de-avena-alitey-3","status":"publish","type":"product","link":"https:\/\/iber.market\/en\/product\/bebida-de-avena-alitey-3\/","title":{"rendered":"Alitey oat drink"},"content":{"rendered":"<p>Bebida de avena Alitey es una opci\u00f3n perfecta para quienes quieren seguir disfrutando de sabores habituales de Espa\u00f1a viviendo en Europa o para cualquier persona que aprecie la alimentaci\u00f3n espa\u00f1ola. Su formato pack-6 lo hace pr\u00e1ctico para el d\u00eda a d\u00eda, reuniones o consumo habitual. Un producto pensado para mantener el v\u00ednculo con la gastronom\u00eda espa\u00f1ola, f\u00e1cil de integrar en compras internacionales y con el car\u00e1cter de los productos que se consumen habitualmente en Espa\u00f1a.<\/p>","protected":false},"excerpt":{"rendered":"<p>Disfruta de Bebida de avena Alitey con aut\u00e9ntico sabor espa\u00f1ol. Ideal para expatriados y amantes de la gastronom\u00eda espa\u00f1ola en Europa. Formato pack-6.<\/p>","protected":false},"featured_media":195024,"template":"","meta":[],"product_brand":[],"product_cat":[353],"product_tag":[],"class_list":{"0":"post-195023","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-bebidas-ecologicas","8":"first","9":"instock","10":"taxable","11":"shipping-taxable","12":"purchasable","13":"product-type-simple"},"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/iber.market\/en\/wp-json\/wp\/v2\/product\/195023","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/iber.market\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/iber.market\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/iber.market\/en\/wp-json\/wp\/v2\/media\/195024"}],"wp:attachment":[{"href":"https:\/\/iber.market\/en\/wp-json\/wp\/v2\/media?parent=195023"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/iber.market\/en\/wp-json\/wp\/v2\/product_brand?post=195023"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/iber.market\/en\/wp-json\/wp\/v2\/product_cat?post=195023"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/iber.market\/en\/wp-json\/wp\/v2\/product_tag?post=195023"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}