{"id":192315,"date":"2026-02-17T08:56:59","date_gmt":"2026-02-17T08:56:59","guid":{"rendered":"https:\/\/iber.market\/producto\/cava-semi-seco-freixenet\/"},"modified":"2026-03-03T13:50:46","modified_gmt":"2026-03-03T13:50:46","slug":"cava-semi-seco-freixenet","status":"publish","type":"product","link":"https:\/\/iber.market\/en\/product\/cava-semi-seco-freixenet\/","title":{"rendered":"Freixenet semi dry cava"},"content":{"rendered":"<p>Cava semi seco Freixenet es una excelente opci\u00f3n para quienes buscan productos t\u00edpicos de Espa\u00f1a en Europa. Pensado especialmente para expatriados, residentes europeos o cualquier amante de la gastronom\u00eda y bebidas espa\u00f1olas, este producto destaca por su calidad, sabor aut\u00e9ntico y tradici\u00f3n. Perfecto para compartir, regalar o disfrutar en casa con la esencia del estilo de vida espa\u00f1ol.<\/p>","protected":false},"excerpt":{"rendered":"<p>Cava semi seco Freixenet ideal para disfrutar del aut\u00e9ntico sabor de Espa\u00f1a. Perfecto para expatriados y amantes europeos de la gastronom\u00eda y bebidas espa\u00f1olas.<\/p>","protected":false},"featured_media":192316,"template":"","meta":[],"product_brand":[],"product_cat":[375],"product_tag":[],"class_list":{"0":"post-192315","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-cavas-y-espumosos","8":"first","9":"instock","10":"taxable","11":"shipping-taxable","12":"purchasable","13":"product-type-simple"},"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/iber.market\/en\/wp-json\/wp\/v2\/product\/192315","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/iber.market\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/iber.market\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/iber.market\/en\/wp-json\/wp\/v2\/media\/192316"}],"wp:attachment":[{"href":"https:\/\/iber.market\/en\/wp-json\/wp\/v2\/media?parent=192315"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/iber.market\/en\/wp-json\/wp\/v2\/product_brand?post=192315"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/iber.market\/en\/wp-json\/wp\/v2\/product_cat?post=192315"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/iber.market\/en\/wp-json\/wp\/v2\/product_tag?post=192315"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}