{"id":192222,"date":"2026-02-17T08:56:33","date_gmt":"2026-02-17T08:56:33","guid":{"rendered":"https:\/\/iber.market\/producto\/vino-blanco-de-aguja-espumoso-blanc-pescador\/"},"modified":"2026-07-31T07:35:24","modified_gmt":"2026-07-31T07:35:24","slug":"vino-blanco-de-aguja-espumoso-blanc-pescador","status":"publish","type":"product","link":"https:\/\/iber.market\/en\/product\/vino-blanco-de-aguja-espumoso-blanc-pescador\/","title":{"rendered":"Vino blanco de aguja espumoso Blanc Pescador"},"content":{"rendered":"<p>Vino blanco de aguja espumoso Blanc Pescador es una excelente opci\u00f3n para quienes buscan productos t\u00edpicos de Espa\u00f1a en Europa. Pensado especialmente para expatriados, residentes europeos o cualquier amante de la gastronom\u00eda y bebidas espa\u00f1olas, este producto destaca por su calidad, sabor aut\u00e9ntico y tradici\u00f3n. Perfecto para compartir, regalar o disfrutar en casa con la esencia del estilo de vida espa\u00f1ol.<\/p>","protected":false},"excerpt":{"rendered":"<p>Vino blanco de aguja espumoso Blanc Pescador ideal para disfrutar del aut\u00e9ntico sabor de Espa\u00f1a. Perfecto para expatriados y amantes europeos de la gastronom\u00eda y bebidas espa\u00f1olas.<\/p>","protected":false},"featured_media":192223,"template":"","meta":[],"product_brand":[],"product_cat":[375],"product_tag":[],"class_list":["post-192222","product","type-product","status-publish","has-post-thumbnail","product_cat-cavas-y-espumosos","first","instock","taxable","shipping-taxable","purchasable","product-type-simple"],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/iber.market\/en\/wp-json\/wp\/v2\/product\/192222","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/iber.market\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/iber.market\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/iber.market\/en\/wp-json\/wp\/v2\/media\/192223"}],"wp:attachment":[{"href":"https:\/\/iber.market\/en\/wp-json\/wp\/v2\/media?parent=192222"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/iber.market\/en\/wp-json\/wp\/v2\/product_brand?post=192222"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/iber.market\/en\/wp-json\/wp\/v2\/product_cat?post=192222"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/iber.market\/en\/wp-json\/wp\/v2\/product_tag?post=192222"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}