{"id":200866,"date":"2026-03-03T14:17:08","date_gmt":"2026-03-03T14:17:08","guid":{"rendered":"https:\/\/iber.market\/producto\/bebida-cider-con-gas-spieler-sabor-a-manzana-2\/"},"modified":"2026-03-03T14:17:09","modified_gmt":"2026-03-03T14:17:09","slug":"bebida-cider-con-gas-spieler-sabor-a-manzana-2","status":"publish","type":"product","link":"https:\/\/iber.market\/de\/product\/bebida-cider-con-gas-spieler-sabor-a-manzana-2\/","title":{"rendered":"Sprudelgetr\u00e4nk Apfelwein Spieler Apfelgeschmack"},"content":{"rendered":"<p>Bebida cider con gas Spieler sabor a manzana es una excelente opci\u00f3n para quienes buscan productos t\u00edpicos de Espa\u00f1a en Europa. Pensado especialmente para expatriados, residentes europeos o cualquier amante de la gastronom\u00eda y bebidas espa\u00f1olas, este producto destaca por su calidad, sabor aut\u00e9ntico y tradici\u00f3n. Perfecto para compartir, regalar o disfrutar en casa con la esencia del estilo de vida espa\u00f1ol.<\/p>","protected":false},"excerpt":{"rendered":"<p>Bebida cider con gas Spieler sabor a manzana ideal para disfrutar del aut\u00e9ntico sabor de Espa\u00f1a. Perfecto para expatriados y amantes europeos de la gastronom\u00eda y bebidas espa\u00f1olas.<\/p>","protected":false},"featured_media":200867,"template":"","meta":[],"product_brand":[],"product_cat":[47],"product_tag":[],"class_list":{"0":"post-200866","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-cervezas-espanolas","8":"first","9":"instock","10":"taxable","11":"shipping-taxable","12":"purchasable","13":"product-type-simple"},"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/iber.market\/de\/wp-json\/wp\/v2\/product\/200866","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/iber.market\/de\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/iber.market\/de\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/iber.market\/de\/wp-json\/wp\/v2\/media\/200867"}],"wp:attachment":[{"href":"https:\/\/iber.market\/de\/wp-json\/wp\/v2\/media?parent=200866"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/iber.market\/de\/wp-json\/wp\/v2\/product_brand?post=200866"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/iber.market\/de\/wp-json\/wp\/v2\/product_cat?post=200866"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/iber.market\/de\/wp-json\/wp\/v2\/product_tag?post=200866"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}