{"id":197942,"date":"2026-02-24T03:53:30","date_gmt":"2026-02-24T03:53:30","guid":{"rendered":"https:\/\/iber.market\/producto\/tonico-facial-vitaminas-y-minerales-facial-clean-hidratante-y-regenerador\/"},"modified":"2026-06-04T06:56:07","modified_gmt":"2026-06-04T06:56:07","slug":"tonico-facial-vitaminas-y-minerales-facial-clean-hidratante-y-regenerador","status":"publish","type":"product","link":"https:\/\/iber.market\/de\/product\/tonico-facial-vitaminas-y-minerales-facial-clean-hidratante-y-regenerador\/","title":{"rendered":"T\u00f3nico facial vitaminas y minerales Facial Clean hidratante y regenerador"},"content":{"rendered":"<p>T\u00f3nico facial vitaminas y minerales Facial Clean hidratante y regenerador es una excelente opci\u00f3n para quienes viven fuera de Espa\u00f1a y quieren seguir utilizando productos de higiene y cuidado personal similares a los que se encuentran habitualmente en el mercado espa\u00f1ol. Pensado para expatriados espa\u00f1oles en Europa y consumidores que valoran la calidad y tradici\u00f3n de los productos espa\u00f1oles, ofreciendo comodidad y confianza en el cuidado diario.<\/p>","protected":false},"excerpt":{"rendered":"<p>T\u00f3nico facial vitaminas y minerales Facial Clean hidratante y regenerador con calidad inspirada en el cuidado personal habitual en Espa\u00f1a. Ideal para expatriados en Europa y amantes de los productos espa\u00f1oles.<\/p>","protected":false},"featured_media":197943,"template":"","meta":[],"product_brand":[],"product_cat":[365],"product_tag":[],"class_list":{"0":"post-197942","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-cuidado-corporal-y-facial","8":"first","9":"instock","10":"taxable","11":"shipping-taxable","12":"purchasable","13":"product-type-simple"},"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/iber.market\/de\/wp-json\/wp\/v2\/product\/197942","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/iber.market\/de\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/iber.market\/de\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/iber.market\/de\/wp-json\/wp\/v2\/media\/197943"}],"wp:attachment":[{"href":"https:\/\/iber.market\/de\/wp-json\/wp\/v2\/media?parent=197942"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/iber.market\/de\/wp-json\/wp\/v2\/product_brand?post=197942"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/iber.market\/de\/wp-json\/wp\/v2\/product_cat?post=197942"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/iber.market\/de\/wp-json\/wp\/v2\/product_tag?post=197942"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}