{"id":195557,"date":"2026-02-21T22:28:52","date_gmt":"2026-02-21T22:28:52","guid":{"rendered":"https:\/\/iber.market\/producto\/agua-mineral-grande-bezoya\/"},"modified":"2026-06-04T07:00:49","modified_gmt":"2026-06-04T07:00:49","slug":"agua-mineral-grande-bezoya","status":"publish","type":"product","link":"https:\/\/iber.market\/de\/product\/agua-mineral-grande-bezoya\/","title":{"rendered":"Bezoya gro\u00dfes Mineralwasser"},"content":{"rendered":"<p>Agua mineral grande Bezoya es una opci\u00f3n perfecta para quienes quieren seguir disfrutando de sabores habituales de Espa\u00f1a viviendo en Europa o para cualquier persona que aprecie la alimentaci\u00f3n espa\u00f1ola. Su formato botella lo hace pr\u00e1ctico para el d\u00eda a d\u00eda, reuniones o consumo habitual. Un producto pensado para mantener el v\u00ednculo con la gastronom\u00eda espa\u00f1ola, f\u00e1cil de integrar en compras internacionales y con el car\u00e1cter de los productos que se consumen habitualmente en Espa\u00f1a.<\/p>","protected":false},"excerpt":{"rendered":"<p>Disfruta de Agua mineral grande Bezoya con aut\u00e9ntico sabor espa\u00f1ol. Ideal para expatriados y amantes de la gastronom\u00eda espa\u00f1ola en Europa. Formato botella.<\/p>","protected":false},"featured_media":195558,"template":"","meta":[],"product_brand":[],"product_cat":[67],"product_tag":[],"class_list":{"0":"post-195557","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-agua","8":"first","9":"instock","10":"taxable","11":"shipping-taxable","12":"purchasable","13":"product-type-simple"},"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/iber.market\/de\/wp-json\/wp\/v2\/product\/195557","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/iber.market\/de\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/iber.market\/de\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/iber.market\/de\/wp-json\/wp\/v2\/media\/195558"}],"wp:attachment":[{"href":"https:\/\/iber.market\/de\/wp-json\/wp\/v2\/media?parent=195557"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/iber.market\/de\/wp-json\/wp\/v2\/product_brand?post=195557"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/iber.market\/de\/wp-json\/wp\/v2\/product_cat?post=195557"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/iber.market\/de\/wp-json\/wp\/v2\/product_tag?post=195557"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}