{"id":192339,"date":"2026-02-17T08:57:11","date_gmt":"2026-02-17T08:57:11","guid":{"rendered":"https:\/\/iber.market\/producto\/cava-brut-cabre-sabate\/"},"modified":"2026-03-03T13:50:48","modified_gmt":"2026-03-03T13:50:48","slug":"cava-brut-cabre-sabate","status":"publish","type":"product","link":"https:\/\/iber.market\/de\/product\/cava-brut-cabre-sabate\/","title":{"rendered":"Cava brut Cabr\u00e9 &amp; Sabat\u00e9"},"content":{"rendered":"<p>Cava brut Cabr\u00e9 &#038; Sabat\u00e9 es una excelente opci\u00f3n para quienes buscan productos t\u00edpicos de Espa\u00f1a en Europa. Pensado especialmente para expatriados, residentes europeos o cualquier amante de la gastronom\u00eda y bebidas espa\u00f1olas, este producto destaca por su calidad, sabor aut\u00e9ntico y tradici\u00f3n. Perfecto para compartir, regalar o disfrutar en casa con la esencia del estilo de vida espa\u00f1ol.<\/p>","protected":false},"excerpt":{"rendered":"<p>Cava brut Cabr\u00e9 &#038; Sabat\u00e9 ideal para disfrutar del aut\u00e9ntico sabor de Espa\u00f1a. Perfecto para expatriados y amantes europeos de la gastronom\u00eda y bebidas espa\u00f1olas.<\/p>","protected":false},"featured_media":192340,"template":"","meta":[],"product_brand":[],"product_cat":[375],"product_tag":[],"class_list":{"0":"post-192339","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-cavas-y-espumosos","8":"first","9":"instock","10":"taxable","11":"shipping-taxable","12":"purchasable","13":"product-type-simple"},"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/iber.market\/de\/wp-json\/wp\/v2\/product\/192339","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/iber.market\/de\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/iber.market\/de\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/iber.market\/de\/wp-json\/wp\/v2\/media\/192340"}],"wp:attachment":[{"href":"https:\/\/iber.market\/de\/wp-json\/wp\/v2\/media?parent=192339"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/iber.market\/de\/wp-json\/wp\/v2\/product_brand?post=192339"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/iber.market\/de\/wp-json\/wp\/v2\/product_cat?post=192339"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/iber.market\/de\/wp-json\/wp\/v2\/product_tag?post=192339"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}